{"id":35592,"date":"2025-10-15T14:14:25","date_gmt":"2025-10-15T12:14:25","guid":{"rendered":"https:\/\/nbn23.com\/nbn-home-page-fiba\/"},"modified":"2025-10-16T10:06:52","modified_gmt":"2025-10-16T08:06:52","slug":"nbn-home-page-fiba","status":"publish","type":"page","link":"https:\/\/nbn23.com\/it\/","title":{"rendered":"NBN Home Page FIBA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"35592\" class=\"elementor elementor-35592 elementor-35389\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8b532c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8b532c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f7a2a1\" data-id=\"9f7a2a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e677b5d elementor-widget__width-initial elementor-widget elementor-widget-html\" data-id=\"e677b5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!DOCTYPE html><br><html lang=\"it\"><br><head>\r\n  <meta charset=\"UTF-8\" \/>\r\n  <meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\" \/>\r\n  <title>NBN23 \u00d7 Approvazione FIBA<\/title>\r\n  <link rel=\"stylesheet\" href=\"style.css\" \/>\r\n<\/head><br><body><br><br>  <!-- HERO --><br>  <section class=\"hero\">\r\n  <video autoplay muted loop playsinline class=\"hero-video\">\r\n    <source src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/Banner-Website-video-1.mp4\" type=\"video\/mp4\">\r\n  <\/video>\r\n\r\n  <div class=\"hero-overlay\"><\/div>\r\n\r\n  <div class=\"hero-content\">\r\n    <h1>Ufficialmente approvato da <span class=\"highlight\">FIBA<\/span><\/h1>\r\n\r\n    <p class=\"hero-subtext\">\r\n      Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi.\r\n    <\/p>\r\n\r\n    <div class=\"fiba-center\">\r\n      <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/FIBA-endorsed-1.png\" alt=\"Logo FIBA\" class=\"fiba-logo\">\r\n    <\/div>\r\n\r\n    <div class=\"hero-logos\">\r\n      <div class=\"logo-item\">\r\n        <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/Logo-Swish-whit.png\" alt=\"Logo Swish\">\r\n      <\/div>\r\n      <div class=\"logo-item\">\r\n        <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/Inagme-logo-e1760449173398.png\" alt=\"Logo InGame\">\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"hero-buttons\">\r\n      <a href=\"https:\/\/swishbynbn23.com\/de\" class=\"btn orange\">Scopri Swish<\/a>\r\n      <a href=\"https:\/\/nbn23.com\/it\/ingame\/\" class=\"btn blue\">Scopri InGame<\/a>\r\n      <a href=\"https:\/\/nbn23.com\/it\/dai-campetti-locali-allo-standard-globale-nbn23-e-ora-ufficialmente-riconosciuta-dalla-fiba\/\" class=\"btn dark\">Leggi l'annuncio FIBA<\/a>\r\n    <\/div>\r\n  <\/div>\r\n<\/section><br><br><section class=\"trust-section\">\r\n  <h2>Scelto da federazioni, leghe e club<\/h2>\r\n\r\n  <div class=\"trust-stats\">\r\n    <div class=\"trust-box\">\r\n      <span class=\"highlight\">900.000+<\/span>\r\n      <p>Partite<\/p>\r\n    <\/div>\r\n    <div class=\"trust-box\">\r\n      <span class=\"highlight\">70+<\/span>\r\n      <p>Paesi<\/p>\r\n    <\/div>\r\n    <div class=\"trust-box\">\r\n      <span class=\"highlight\">3.000+<\/span>\r\n      <p>Competizioni<\/p>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"trust-logos\">\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/12.png\" alt=\"FIBA\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/swiss-1.png\" alt=\"Basket Svizzero\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/9.png\" alt=\"DBB\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/8.png\" alt=\"Jr. NBA\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/1.png\" alt=\"FIP Italia\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/3-1.png\" alt=\"Basket Repubblica Ceca\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/2.png\" alt=\"Federazione Canarie\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/11.png\" alt=\"Basket Portogallo\" \/>\r\n    <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/01\/4.png\" alt=\"RYZE\" \/>\r\n  <\/div>\r\n<\/section><br><br><!-- SWISH --><br><section class=\"product swish\">\r\n  <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/Swish-icon.png\" alt=\"Icona Swish\">\r\n  <div class=\"text\">\r\n    <h2>Swish. Tutto il basket, tutte le statistiche.<\/h2>\r\n    <p>Swish connette tifosi, giocatori e federazioni con dati in tempo reale e tracciamento live delle partite. La tua casa digitale per il basket.<\/p>\r\n    <ul>\r\n      <li>Statistiche live per ogni partita<\/li>\r\n      <li>Segui i tuoi giocatori e team preferiti<\/li>\r\n      <li>Disponibile in tutto il mondo<\/li>\r\n    <\/ul>\r\n    <a href=\"https:\/\/swishbynbn23.com\/de\" class=\"btn primary\">Scopri Swish<\/a>\r\n  <\/div>\r\n<\/section><br><br><!-- INGAME --><br><section class=\"product ingame\">\r\n  <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/Ingame-icon.png\" alt=\"Icona InGame\">\r\n  <div class=\"text\">\r\n    <h2>InGame. Il referto digitale per ogni campo.<\/h2>\r\n    <p>InGame sostituisce la carta con un'app semplice e conforme agli standard FIBA. Registra tutte le statistiche in tempo reale e si connette automaticamente ai database federali.<\/p>\r\n    <ul>\r\n      <li>Raccolta rapida e precisa dei dati<\/li>\r\n      <li>Integrazione diretta con le federazioni<\/li>\r\n      <li>Funziona offline in qualsiasi palestra<\/li>\r\n    <\/ul>\r\n    <a href=\"https:\/\/nbn23.com\/it\/ingame\/\" class=\"btn secondary\">Scopri InGame<\/a>\r\n  <\/div>\r\n<\/section><br><br><!-- FIBA ANNOUNCEMENT --><br><section class=\"fiba\">\r\n  <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/02\/javi.jpg\" alt=\"Javier Bosch\" class=\"ceo\">\r\n  <h2>Approvazione FIBA. Riconoscimento globale con un focus sulla crescita giovanile.<\/h2>\r\n  <p>Questa partnership conferma lo standard che abbiamo costruito per ufficiali e organizzatori. Mette al centro visibilit\u00e0 e sviluppo.<\/p>\r\n  <a href=\"https:\/\/nbn23.com\/it\/dai-campetti-locali-allo-standard-globale-nbn23-e-ora-ufficialmente-riconosciuta-dalla-fiba\/\" class=\"btn primary\">Leggi l'annuncio completo<\/a>\r\n<\/section><br><br><!-- PARTNER TESTIMONIALS --><br><section class=\"partners\">\r\n  <h2>Federazioni che collaborano con NBN23<\/h2>\r\n\r\n  <div class=\"testimonials\">\r\n    <div class=\"testimonial\">\r\n      <div class=\"logo-band\">\r\n        <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/DBB_logo.png\" alt=\"Logo DBB\" class=\"partner-logo\">\r\n      <\/div>\r\n      <p>\u201cLa nostra collaborazione con NBN23 \u00e8 caratterizzata da professionalit\u00e0, innovazione e una profonda comprensione delle esigenze di una federazione nazionale. I loro strumenti hanno semplificato la gestione del punteggio e delle competizioni a tutti i livelli, e il loro team fornisce un supporto eccellente. NBN23 \u00e8 molto pi\u00f9 di un fornitore tecnologico: \u00e8 un partner fidato per il futuro digitale del basket tedesco.\u201d<\/p>\r\n      <h4>Jochen B\u00f6hmcker<\/h4>\r\n      <span>Responsabile Competizioni, Federazione Tedesca di Pallacanestro (DBB)<\/span>\r\n    <\/div>\r\n\r\n    <div class=\"testimonial\">\r\n      <div class=\"logo-band\">\r\n        <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2023\/08\/icon-app.png\" alt=\"Logo FIP\" class=\"partner-logo\">\r\n      <\/div>\r\n      <p>\u201cCollaborare con NBN23 \u00e8 stato un passo fondamentale per modernizzare la gestione del basket in Italia. I loro strumenti digitali hanno migliorato l\u2019efficienza, la precisione e l\u2019accessibilit\u00e0 delle nostre competizioni. La professionalit\u00e0, l\u2019innovazione e la profonda conoscenza dello sport rendono NBN23 un partner prezioso per la FIP.\u201d<\/p>\r\n      <h4>Graziano Martinelli<\/h4>\r\n      <span>Vice Segretario, Federazione Italiana Pallacanestro (FIP)<\/span>\r\n    <\/div>\r\n\r\n    <div class=\"testimonial\">\r\n      <div class=\"logo-band\">\r\n        <img decoding=\"async\" src=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/Untitled-design-17.png\" alt=\"Logo Federazione Portoghese\" class=\"partner-logo\">\r\n      <\/div>\r\n      <p>\u201cLe piattaforme InGame e Swish di NBN23 sono diventate strumenti fondamentali nelle nostre attivit\u00e0. Hanno semplificato la gestione delle partite, fornito statistiche in tempo reale e connesso tifosi e giocatori come mai prima. Apprezziamo la loro qualit\u00e0, affidabilit\u00e0 e costante miglioramento. NBN23 \u00e8 un partner indispensabile per il basket portoghese.\u201d<\/p>\r\n      <h4>Lu\u00eds Veiga<\/h4>\r\n      <span>Vicepresidente, Federazione Portoghese di Pallacanestro (FPB)<\/span>\r\n    <\/div>\r\n  <\/div>\r\n<\/section><br><br><!-- CTA --><br><section class=\"cta-final\">\r\n  <h2>Unisciti al movimento globale del basket digitale<\/h2>\r\n  <p>Utilizza strumenti approvati da FIBA e scelti da federazioni in tutto il mondo.<\/p>\r\n  <div class=\"cta-buttons\">\r\n    <a href=\"https:\/\/swishbynbn23.com\/de\" class=\"btn orange\">Scopri Swish<\/a>\r\n    <a href=\"https:\/\/nbn23.com\/it\/ingame\/\" class=\"btn blue\">Scopri InGame<\/a>\r\n    <a href=\"mailto:irene.gari@nbn23.tech\" class=\"btn dark\">Scrivi a Irene<\/a>\r\n  <\/div>\r\n<\/section><br>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri Swish Scopri InGame Leggi l&#8217;annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Swish. Tutto il basket, tutte le [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":35305,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-35592","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l&#039;annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nbn23.com\/it\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NBN23 - We are technology, we are basketball\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"NBN Home Page FIBA - NBN23\" \/>\n\t\t<meta property=\"og:description\" content=\"NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l&#039;annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nbn23.com\/it\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"3300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2475\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-10-15T12:14:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-16T08:06:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:title\" content=\"NBN Home Page FIBA - NBN23\" \/>\n\t\t<meta name=\"twitter:description\" content=\"NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l&#039;annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/FIBA-Blog-Javi.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nbn23.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#listItem\",\"name\":\"NBN Home Page FIBA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#listItem\",\"position\":2,\"name\":\"NBN Home Page FIBA\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#organization\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"url\":\"https:\\\/\\\/nbn23.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Artboard-5.png\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#organizationLogo\",\"width\":158,\"height\":158},\"image\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/swishallhoops?lang=en\",\"https:\\\/\\\/www.instagram.com\\\/swishallhoops\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#webpage\",\"url\":\"https:\\\/\\\/nbn23.com\\\/it\\\/\",\"name\":\"NBN Home Page FIBA - NBN23\",\"description\":\"NBN23 \\u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l'annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/FIBA-Blog-Javi.png\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#mainImage\",\"width\":1920,\"height\":1080,\"caption\":\"digital scoresheet and Fan stat app, Basketball, Swish, INGame, FIBA endorsed\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#mainImage\"},\"datePublished\":\"2025-10-15T14:14:25+02:00\",\"dateModified\":\"2025-10-16T10:06:52+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/nbn23.com\\\/it\\\/\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"NBN Home Page FIBA - NBN23","description":"NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l'annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi","canonical_url":"https:\/\/nbn23.com\/it\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/nbn23.com\/it\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nbn23.com\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/nbn23.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/it\/#listItem","name":"NBN Home Page FIBA"}},{"@type":"ListItem","@id":"https:\/\/nbn23.com\/it\/#listItem","position":2,"name":"NBN Home Page FIBA","previousItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/it\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/nbn23.com\/it\/#organization","name":"NBN23","description":"We are technology, we are basketball","url":"https:\/\/nbn23.com\/it\/","logo":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/03\/Artboard-5.png","@id":"https:\/\/nbn23.com\/it\/#organizationLogo","width":158,"height":158},"image":{"@id":"https:\/\/nbn23.com\/it\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/swishallhoops?lang=en","https:\/\/www.instagram.com\/swishallhoops\/"]},{"@type":"WebPage","@id":"https:\/\/nbn23.com\/it\/#webpage","url":"https:\/\/nbn23.com\/it\/","name":"NBN Home Page FIBA - NBN23","description":"NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l'annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/nbn23.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/nbn23.com\/it\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/FIBA-Blog-Javi.png","@id":"https:\/\/nbn23.com\/it\/#mainImage","width":1920,"height":1080,"caption":"digital scoresheet and Fan stat app, Basketball, Swish, INGame, FIBA endorsed"},"primaryImageOfPage":{"@id":"https:\/\/nbn23.com\/it\/#mainImage"},"datePublished":"2025-10-15T14:14:25+02:00","dateModified":"2025-10-16T10:06:52+02:00"},{"@type":"WebSite","@id":"https:\/\/nbn23.com\/it\/#website","url":"https:\/\/nbn23.com\/it\/","name":"NBN23","description":"We are technology, we are basketball","inLanguage":"it-IT","publisher":{"@id":"https:\/\/nbn23.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"NBN23 - We are technology, we are basketball","og:type":"article","og:title":"NBN Home Page FIBA - NBN23","og:description":"NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l'annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi","og:url":"https:\/\/nbn23.com\/it\/","og:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:secure_url":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:width":3300,"og:image:height":2475,"article:published_time":"2025-10-15T12:14:25+00:00","article:modified_time":"2025-10-16T08:06:52+00:00","twitter:card":"summary_large_image","twitter:site":"@swishallhoops","twitter:title":"NBN Home Page FIBA - NBN23","twitter:description":"NBN23 \u00d7 Approvazione FIBA Ufficialmente approvato da FIBA Potenziamo il basket giovanile e di base con statistiche in tempo reale, referti digitali e un\u2019esperienza connessa per federazioni, giocatori e tifosi. Scopri InGame Leggi l'annuncio FIBA Scelto da federazioni, leghe e club 900.000+ Partite 70+ Paesi 3.000+ Competizioni Federazioni che collaborano con NBN23 Scopri InGame Scrivi","twitter:creator":"@swishallhoops","twitter:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2025\/10\/FIBA-Blog-Javi.png"},"aioseo_meta_data":{"post_id":"35592","title":"#post_title #separator_sa #site_title","description":"#post_content","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-10-15 12:14:25","updated":"2025-10-16 08:07:41","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nbn23.com\/it\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNBN Home Page FIBA\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nbn23.com\/it\/"},{"label":"NBN Home Page FIBA","link":"https:\/\/nbn23.com\/it\/"}],"_links":{"self":[{"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/pages\/35592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/comments?post=35592"}],"version-history":[{"count":2,"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/pages\/35592\/revisions"}],"predecessor-version":[{"id":35605,"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/pages\/35592\/revisions\/35605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/media\/35305"}],"wp:attachment":[{"href":"https:\/\/nbn23.com\/it\/wp-json\/wp\/v2\/media?parent=35592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}