{"id":6915,"date":"2020-01-14T11:41:20","date_gmt":"2020-01-14T09:41:20","guid":{"rendered":"https:\/\/nbn23.com\/?p=6915"},"modified":"2020-11-16T10:31:59","modified_gmt":"2020-11-16T08:31:59","slug":"nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/","title":{"rendered":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS"},"content":{"rendered":"\n<p><em>La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su\u00a0software\u00a0dedicado a la nataci\u00f3n en los centros YMCA de este territorio.\u00a0<\/em><\/p>\n\n\n\n<p>NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos.\u00a0<strong>La tecnol\u00f3gica valenciana ha abierto una ronda con la que espera levantar 2,5 millones de euros,<\/strong>\u00a0que se destinar\u00e1n a reforzar su equipo y financiar la expansi\u00f3n de Nagi, su\u00a0<em>software<\/em>\u00a0de nataci\u00f3n, en el mercado norteamericano.<\/p>\n\n\n\n<p>Leer m\u00e1s: <em>https:\/\/www.palco23.com\/equipamiento\/nbn23-ultima-una-nueva-ronda-de-25-millones-de-euros-para-potenciar-su-expansion-en-eeuu.html<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su\u00a0software\u00a0dedicado a la nataci\u00f3n en los centros YMCA de este territorio.\u00a0 NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos.\u00a0La tecnol\u00f3gica valenciana ha abierto una ronda con la que [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":6916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-6915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su software dedicado a la nataci\u00f3n en los centros YMCA de este territorio. NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\u00f3gica valenciana ha abierto una ronda con la que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Natalia Torres\"\/>\n\t<meta name=\"google-site-verification\" content=\"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NBN23 - We are technology, we are basketball\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23\" \/>\n\t\t<meta property=\"og:description\" content=\"La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su software dedicado a la nataci\u00f3n en los centros YMCA de este territorio. NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\u00f3gica valenciana ha abierto una ronda con la que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"3300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2475\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-14T09:41:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-16T08:31:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:title\" content=\"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su software dedicado a la nataci\u00f3n en los centros YMCA de este territorio. NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\u00f3gica valenciana ha abierto una ronda con la que\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/66263d1a-082b-4c40-95a0-61d207230581.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#blogposting\",\"name\":\"NBN23 PREPARA UNA RONDA DE INVERSI\\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23\",\"headline\":\"NBN23 PREPARA UNA RONDA DE INVERSI\\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS\",\"author\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/66263d1a-082b-4c40-95a0-61d207230581.jpg\",\"width\":1600,\"height\":1200},\"datePublished\":\"2020-01-14T11:41:20+02:00\",\"dateModified\":\"2020-11-16T10:31:59+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#webpage\"},\"articleSection\":\"Prensa, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/#listItem\",\"name\":\"Prensa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/#listItem\",\"position\":2,\"name\":\"Prensa\",\"item\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#listItem\",\"name\":\"NBN23 PREPARA UNA RONDA DE INVERSI\\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#listItem\",\"position\":3,\"name\":\"NBN23 PREPARA UNA RONDA DE INVERSI\\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/#listItem\",\"name\":\"Prensa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Artboard-5.png\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#organizationLogo\",\"width\":158,\"height\":158},\"image\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/swishallhoops?lang=en\",\"https:\\\/\\\/www.instagram.com\\\/swishallhoops\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/\",\"name\":\"Natalia Torres\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#webpage\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/\",\"name\":\"NBN23 PREPARA UNA RONDA DE INVERSI\\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23\",\"description\":\"La tecnol\\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\\u00f1a y Estados Unidos, utilizar\\u00e1 el capital para acelerar la expansi\\u00f3n de Nagi, su software dedicado a la nataci\\u00f3n en los centros YMCA de este territorio. NBN23 busca m\\u00e1s m\\u00fasculo econ\\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\\u00f3gica valenciana ha abierto una ronda con la que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/66263d1a-082b-4c40-95a0-61d207230581.jpg\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#mainImage\",\"width\":1600,\"height\":1200},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\\\/#mainImage\"},\"datePublished\":\"2020-01-14T11:41:20+02:00\",\"dateModified\":\"2020-11-16T10:31:59+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23","description":"La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su software dedicado a la nataci\u00f3n en los centros YMCA de este territorio. NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\u00f3gica valenciana ha abierto una ronda con la que","canonical_url":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#blogposting","name":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23","headline":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS","author":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"publisher":{"@id":"https:\/\/nbn23.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/66263d1a-082b-4c40-95a0-61d207230581.jpg","width":1600,"height":1200},"datePublished":"2020-01-14T11:41:20+02:00","dateModified":"2020-11-16T10:31:59+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#webpage"},"isPartOf":{"@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#webpage"},"articleSection":"Prensa, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/nbn23.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/prensa\/#listItem","name":"Prensa"}},{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/prensa\/#listItem","position":2,"name":"Prensa","item":"https:\/\/nbn23.com\/es\/category\/prensa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#listItem","name":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#listItem","position":3,"name":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS","previousItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/prensa\/#listItem","name":"Prensa"}}]},{"@type":"Organization","@id":"https:\/\/nbn23.com\/es\/#organization","name":"NBN23","description":"We are technology, we are basketball","url":"https:\/\/nbn23.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/03\/Artboard-5.png","@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#organizationLogo","width":158,"height":158},"image":{"@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/swishallhoops?lang=en","https:\/\/www.instagram.com\/swishallhoops\/"]},{"@type":"Person","@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author","url":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/","name":"Natalia Torres"},{"@type":"WebPage","@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#webpage","url":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/","name":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23","description":"La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su software dedicado a la nataci\u00f3n en los centros YMCA de este territorio. NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\u00f3gica valenciana ha abierto una ronda con la que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/nbn23.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#breadcrumblist"},"author":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"creator":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/66263d1a-082b-4c40-95a0-61d207230581.jpg","@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#mainImage","width":1600,"height":1200},"primaryImageOfPage":{"@id":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/#mainImage"},"datePublished":"2020-01-14T11:41:20+02:00","dateModified":"2020-11-16T10:31:59+02:00"},{"@type":"WebSite","@id":"https:\/\/nbn23.com\/es\/#website","url":"https:\/\/nbn23.com\/es\/","name":"NBN23","description":"We are technology, we are basketball","inLanguage":"es-ES","publisher":{"@id":"https:\/\/nbn23.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"NBN23 - We are technology, we are basketball","og:type":"article","og:title":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23","og:description":"La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su software dedicado a la nataci\u00f3n en los centros YMCA de este territorio. NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\u00f3gica valenciana ha abierto una ronda con la que","og:url":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/","og:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:secure_url":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:width":3300,"og:image:height":2475,"article:published_time":"2020-01-14T09:41:20+00:00","article:modified_time":"2020-11-16T08:31:59+00:00","twitter:card":"summary_large_image","twitter:site":"@swishallhoops","twitter:title":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS - NBN23","twitter:description":"La tecnol\u00f3gica valenciana, que actualmente emplea a treinta personas entre Espa\u00f1a y Estados Unidos, utilizar\u00e1 el capital para acelerar la expansi\u00f3n de Nagi, su software dedicado a la nataci\u00f3n en los centros YMCA de este territorio. NBN23 busca m\u00e1s m\u00fasculo econ\u00f3mico para impulsar su negocio en Estados Unidos. La tecnol\u00f3gica valenciana ha abierto una ronda con la que","twitter:creator":"@swishallhoops","twitter:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/66263d1a-082b-4c40-95a0-61d207230581.jpg"},"aioseo_meta_data":{"post_id":"6915","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-01-12 14:05:36","updated":"2025-06-05 08:15:35","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nbn23.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nbn23.com\/es\/category\/prensa\/\" title=\"Prensa\">Prensa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nbn23.com\/es\/"},{"label":"Prensa","link":"https:\/\/nbn23.com\/es\/category\/prensa\/"},{"label":"NBN23 PREPARA UNA RONDA DE INVERSI\u00d3N PARA EXPANDIRSE EN ESTADOS UNIDOS","link":"https:\/\/nbn23.com\/es\/nbn23-prepara-una-ronda-de-inversion-para-expandirse-en-estados-unidos\/"}],"_links":{"self":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/6915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/comments?post=6915"}],"version-history":[{"count":1,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/6915\/revisions"}],"predecessor-version":[{"id":6921,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/6915\/revisions\/6921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/media\/6916"}],"wp:attachment":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/media?parent=6915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/categories?post=6915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/tags?post=6915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}