{"id":6906,"date":"2020-01-13T13:55:04","date_gmt":"2020-01-13T11:55:04","guid":{"rendered":"https:\/\/nbn23.com\/?p=6906"},"modified":"2020-11-16T10:32:03","modified_gmt":"2020-11-16T08:32:03","slug":"todo-el-baloncesto-en-madrid-es-digital","status":"publish","type":"post","link":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/","title":{"rendered":"TODO EL BALONCESTO EN MADRID ES DIGITAL"},"content":{"rendered":"\n<p>La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital.<\/p>\n\n\n\n<p>Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el deporte de la canasta con Swish, una aplicaci\u00f3n que permite seguir m\u00faltiples competiciones en vivo desde cualquier dispositivo.<\/p>\n\n\n\n<p>Leer m\u00e1s: <a href=\"https:\/\/www.marca.com\/primera-plana\/2020\/01\/11\/5e13a98ae2704e89398b45e0.html\">https:\/\/www.marca.com\/primera-plana\/2020\/01\/11\/5e13a98ae2704e89398b45e0.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":6907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-6906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Natalia Torres\"\/>\n\t<meta name=\"google-site-verification\" content=\"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NBN23 - We are technology, we are basketball\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23\" \/>\n\t\t<meta property=\"og:description\" content=\"La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"3300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2475\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-13T11:55:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-16T08:32:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:title\" content=\"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/Madrid.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#blogposting\",\"name\":\"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23\",\"headline\":\"TODO EL BALONCESTO EN MADRID ES DIGITAL\",\"author\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Madrid.jpg\",\"width\":990,\"height\":557},\"datePublished\":\"2020-01-13T13:55:04+02:00\",\"dateModified\":\"2020-11-16T10:32:03+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#webpage\"},\"articleSection\":\"Prensa, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/#listItem\",\"name\":\"Prensa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/#listItem\",\"position\":2,\"name\":\"Prensa\",\"item\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#listItem\",\"name\":\"TODO EL BALONCESTO EN MADRID ES DIGITAL\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#listItem\",\"position\":3,\"name\":\"TODO EL BALONCESTO EN MADRID ES DIGITAL\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/prensa\\\/#listItem\",\"name\":\"Prensa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Artboard-5.png\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#organizationLogo\",\"width\":158,\"height\":158},\"image\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/swishallhoops?lang=en\",\"https:\\\/\\\/www.instagram.com\\\/swishallhoops\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/\",\"name\":\"Natalia Torres\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#webpage\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/\",\"name\":\"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23\",\"description\":\"La Federaci\\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\\u00f3n del baloncesto y se ha convertido en la primera federaci\\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\\u00f1ola que digitaliza el baloncesto en m\\u00faltiples pa\\u00edses y que ha revolucionado el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Madrid.jpg\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#mainImage\",\"width\":990,\"height\":557},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/todo-el-baloncesto-en-madrid-es-digital\\\/#mainImage\"},\"datePublished\":\"2020-01-13T13:55:04+02:00\",\"dateModified\":\"2020-11-16T10:32:03+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23","description":"La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el","canonical_url":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#blogposting","name":"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23","headline":"TODO EL BALONCESTO EN MADRID ES DIGITAL","author":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"publisher":{"@id":"https:\/\/nbn23.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/Madrid.jpg","width":990,"height":557},"datePublished":"2020-01-13T13:55:04+02:00","dateModified":"2020-11-16T10:32:03+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#webpage"},"isPartOf":{"@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#webpage"},"articleSection":"Prensa, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/nbn23.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/prensa\/#listItem","name":"Prensa"}},{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/prensa\/#listItem","position":2,"name":"Prensa","item":"https:\/\/nbn23.com\/es\/category\/prensa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#listItem","name":"TODO EL BALONCESTO EN MADRID ES DIGITAL"},"previousItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#listItem","position":3,"name":"TODO EL BALONCESTO EN MADRID ES DIGITAL","previousItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/prensa\/#listItem","name":"Prensa"}}]},{"@type":"Organization","@id":"https:\/\/nbn23.com\/es\/#organization","name":"NBN23","description":"We are technology, we are basketball","url":"https:\/\/nbn23.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/03\/Artboard-5.png","@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#organizationLogo","width":158,"height":158},"image":{"@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/swishallhoops?lang=en","https:\/\/www.instagram.com\/swishallhoops\/"]},{"@type":"Person","@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author","url":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/","name":"Natalia Torres"},{"@type":"WebPage","@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#webpage","url":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/","name":"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23","description":"La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/nbn23.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#breadcrumblist"},"author":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"creator":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/Madrid.jpg","@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#mainImage","width":990,"height":557},"primaryImageOfPage":{"@id":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/#mainImage"},"datePublished":"2020-01-13T13:55:04+02:00","dateModified":"2020-11-16T10:32:03+02:00"},{"@type":"WebSite","@id":"https:\/\/nbn23.com\/es\/#website","url":"https:\/\/nbn23.com\/es\/","name":"NBN23","description":"We are technology, we are basketball","inLanguage":"es-ES","publisher":{"@id":"https:\/\/nbn23.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"NBN23 - We are technology, we are basketball","og:type":"article","og:title":"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23","og:description":"La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el","og:url":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/","og:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:secure_url":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:width":3300,"og:image:height":2475,"article:published_time":"2020-01-13T11:55:04+00:00","article:modified_time":"2020-11-16T08:32:03+00:00","twitter:card":"summary_large_image","twitter:site":"@swishallhoops","twitter:title":"TODO EL BALONCESTO EN MADRID ES DIGITAL - NBN23","twitter:description":"La Federaci\u00f3n de Baloncesto de Madrid ha sido pionera en la digitalizaci\u00f3n del baloncesto y se ha convertido en la primera federaci\u00f3n en transmitir sus competiciones en vivo y de forma digital. Lo han hecho de la mano de NBN23, la empresa espa\u00f1ola que digitaliza el baloncesto en m\u00faltiples pa\u00edses y que ha revolucionado el","twitter:creator":"@swishallhoops","twitter:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/01\/Madrid.jpg"},"aioseo_meta_data":{"post_id":"6906","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-01-12 14:04:52","updated":"2025-06-05 08:14:36","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nbn23.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nbn23.com\/es\/category\/prensa\/\" title=\"Prensa\">Prensa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTODO EL BALONCESTO EN MADRID ES DIGITAL\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nbn23.com\/es\/"},{"label":"Prensa","link":"https:\/\/nbn23.com\/es\/category\/prensa\/"},{"label":"TODO EL BALONCESTO EN MADRID ES DIGITAL","link":"https:\/\/nbn23.com\/es\/todo-el-baloncesto-en-madrid-es-digital\/"}],"_links":{"self":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/6906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/comments?post=6906"}],"version-history":[{"count":1,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/6906\/revisions"}],"predecessor-version":[{"id":6912,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/6906\/revisions\/6912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/media\/6907"}],"wp:attachment":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/media?parent=6906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/categories?post=6906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/tags?post=6906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}