{"id":10949,"date":"2021-03-03T09:33:58","date_gmt":"2021-03-03T07:33:58","guid":{"rendered":"https:\/\/nbn23.com\/?p=10949"},"modified":"2021-11-29T11:17:47","modified_gmt":"2021-11-29T09:17:47","slug":"nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish","status":"publish","type":"post","link":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/","title":{"rendered":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH"},"content":{"rendered":"\n<p><em>Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. <\/em><\/p>\n\n\n\n<p>0 acuerdos en 5\na\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido\nNBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha sido la\nFederaci\u00f3n de Baloncesto de Togo que ha firmado con la tecnol\u00f3gica espa\u00f1ola\npara la digitalizaci\u00f3n de sus competiciones.<\/p>\n\n\n\n<p>Con esta firma,\nla Federaci\u00f3n Togolesa se une a las de Guinea y Ben\u00edn que fueron las pioneras\nen firmar con NBN23, y se convierte en la tercera federaci\u00f3n africana que\ncontar\u00e1 con esta tecnolog\u00eda puntera en el planeta baloncesto. El acuerdo\nrubrica la tendencia creciente en este continente de seguir mejorando el basket\ngracias la tecnolog\u00eda.<\/p>\n\n\n\n<p>Con la llegada\nde NBN23, la Federaci\u00f3n de Baloncesto de Togo, no solo consigue un seguimiento\nen vivo y global, sino que adem\u00e1s contar\u00e1 con todas las ventajas que NBN23\ncuenta en su APP: seguimiento de jugadores, seguimiento de equipos, mapas de\ncalor, estad\u00edsticas completas de cada partido, seguimiento jugada a jugada, y\nmuchas m\u00e1s ventajas. Adem\u00e1s, gracias a las \u00faltimas actualizaciones, los fans de\nla Federaci\u00f3n podr\u00e1n ordenar su home (la pantalla inicial) seg\u00fan sus\npreferencias y dispondr\u00e1n de las \u00faltimas informaciones respecto de sus\njugadores o equipos favoritos nada m\u00e1s abrir Swish.<\/p>\n\n\n\n<p>Togo pretende\ndar un salto de calidad y que este crecimiento tecnol\u00f3gico se convierta en un\ncrecimiento deportivo que atraiga talento a su pa\u00eds y que traiga nuevas\ngeneraciones de deportistas centrados en baloncesto. As\u00ed buscar\u00edan mejorar sus\npresencias en el Afrobasket donde cuentan con un 5\u00ba puesto como\nmejor resultado y en el que no participan desde 2011, competici\u00f3n en la que\nregresaron 33 a\u00f1os despu\u00e9s.<\/p>\n\n\n\n<p>Georgio Seeman,\nresponsable de ventas de NBN23 en \u00c1frica, se ha \u201cmostrado realmente satisfecho\ncon la llegada de la Federaci\u00f3n Togolesa a Swish\u201d y adem\u00e1s ha dicho que en las\nconversaciones con los presidentes se observa \u201cel inter\u00e9s que hay en este\ncontinente por hacer crecer el baloncesto a nivel tecnol\u00f3gico, deportivo y\ntambi\u00e9n de visibilidad\u201d.<\/p>\n\n\n\n<p>Goungou Bivaina,\npresidente de la Federaci\u00f3n de Togo, ha hablado sobre la llegada de NBN23:\n\u201cDesde el principio, NBN23 nos ha mostrado mucho inter\u00e9s en trabajar con\nnosotros y ser\u00e1 un placer poder contar con esta tecnolog\u00eda\u201d. \u201cQueremos que el\nbaloncesto togol\u00e9s suba al siguiente nivel y para ello, tenemos que apostar\nfuerte\u201d, inform\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":10950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-10949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Natalia Torres\"\/>\n\t<meta name=\"google-site-verification\" content=\"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NBN23 - We are technology, we are basketball\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH - NBN23\" \/>\n\t\t<meta property=\"og:description\" content=\"Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"3300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2475\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-03-03T07:33:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-11-29T09:17:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:title\" content=\"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH - NBN23\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@swishallhoops\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/nbn23.com\/wp-content\/uploads\/2021\/03\/Federacion-de-Baloncesto-de-Togo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#blogposting\",\"name\":\"NBN23 COGE CARRERILLA EN \\u00c1FRICA: TOGO TAMBI\\u00c9N SE UNIR\\u00c1 A SWISH - NBN23\",\"headline\":\"NBN23 COGE CARRERILLA EN \\u00c1FRICA: TOGO TAMBI\\u00c9N SE UNIR\\u00c1 A SWISH\",\"author\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Federacion-de-Baloncesto-de-Togo.png\",\"width\":1200,\"height\":674},\"datePublished\":\"2021-03-03T09:33:58+02:00\",\"dateModified\":\"2021-11-29T11:17:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#webpage\"},\"articleSection\":\"Noticia, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/noticia\\\/#listItem\",\"name\":\"Noticia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/noticia\\\/#listItem\",\"position\":2,\"name\":\"Noticia\",\"item\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/noticia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#listItem\",\"name\":\"NBN23 COGE CARRERILLA EN \\u00c1FRICA: TOGO TAMBI\\u00c9N SE UNIR\\u00c1 A SWISH\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#listItem\",\"position\":3,\"name\":\"NBN23 COGE CARRERILLA EN \\u00c1FRICA: TOGO TAMBI\\u00c9N SE UNIR\\u00c1 A SWISH\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/category\\\/noticia\\\/#listItem\",\"name\":\"Noticia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Artboard-5.png\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#organizationLogo\",\"width\":158,\"height\":158},\"image\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/swishallhoops?lang=en\",\"https:\\\/\\\/www.instagram.com\\\/swishallhoops\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/\",\"name\":\"Natalia Torres\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#webpage\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/\",\"name\":\"NBN23 COGE CARRERILLA EN \\u00c1FRICA: TOGO TAMBI\\u00c9N SE UNIR\\u00c1 A SWISH - NBN23\",\"description\":\"Tras conseguir las firmas de Guinea y Ben\\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\\u00f3n que ha vivido NBN23 en \\u00c1frica en las \\u00faltimas semanas. La \\u00faltima en unirse a Swish ha\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/author\\\/natalia-torres\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nbn23.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Federacion-de-Baloncesto-de-Togo.png\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#mainImage\",\"width\":1200,\"height\":674},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\\\/#mainImage\"},\"datePublished\":\"2021-03-03T09:33:58+02:00\",\"dateModified\":\"2021-11-29T11:17:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nbn23.com\\\/es\\\/\",\"name\":\"NBN23\",\"description\":\"We are technology, we are basketball\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/nbn23.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH - NBN23","description":"Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha","canonical_url":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"f-oUskwMO1HiKfReO8pcsdJDBUL4hObt1I9W92_I-VE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#blogposting","name":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH - NBN23","headline":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH","author":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"publisher":{"@id":"https:\/\/nbn23.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2021\/03\/Federacion-de-Baloncesto-de-Togo.png","width":1200,"height":674},"datePublished":"2021-03-03T09:33:58+02:00","dateModified":"2021-11-29T11:17:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#webpage"},"isPartOf":{"@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#webpage"},"articleSection":"Noticia, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/nbn23.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/noticia\/#listItem","name":"Noticia"}},{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/noticia\/#listItem","position":2,"name":"Noticia","item":"https:\/\/nbn23.com\/es\/category\/noticia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#listItem","name":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH"},"previousItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#listItem","position":3,"name":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH","previousItem":{"@type":"ListItem","@id":"https:\/\/nbn23.com\/es\/category\/noticia\/#listItem","name":"Noticia"}}]},{"@type":"Organization","@id":"https:\/\/nbn23.com\/es\/#organization","name":"NBN23","description":"We are technology, we are basketball","url":"https:\/\/nbn23.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2020\/03\/Artboard-5.png","@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#organizationLogo","width":158,"height":158},"image":{"@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/swishallhoops?lang=en","https:\/\/www.instagram.com\/swishallhoops\/"]},{"@type":"Person","@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author","url":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/","name":"Natalia Torres"},{"@type":"WebPage","@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#webpage","url":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/","name":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH - NBN23","description":"Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/nbn23.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#breadcrumblist"},"author":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"creator":{"@id":"https:\/\/nbn23.com\/es\/author\/natalia-torres\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/nbn23.com\/wp-content\/uploads\/2021\/03\/Federacion-de-Baloncesto-de-Togo.png","@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#mainImage","width":1200,"height":674},"primaryImageOfPage":{"@id":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/#mainImage"},"datePublished":"2021-03-03T09:33:58+02:00","dateModified":"2021-11-29T11:17:47+02:00"},{"@type":"WebSite","@id":"https:\/\/nbn23.com\/es\/#website","url":"https:\/\/nbn23.com\/es\/","name":"NBN23","description":"We are technology, we are basketball","inLanguage":"es-ES","publisher":{"@id":"https:\/\/nbn23.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"NBN23 - We are technology, we are basketball","og:type":"article","og:title":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH - NBN23","og:description":"Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha","og:url":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/","og:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:secure_url":"https:\/\/nbn23.com\/wp-content\/uploads\/2022\/08\/guy-using-public-bike-with-android-mockup-template-min.png","og:image:width":3300,"og:image:height":2475,"article:published_time":"2021-03-03T07:33:58+00:00","article:modified_time":"2021-11-29T09:17:47+00:00","twitter:card":"summary_large_image","twitter:site":"@swishallhoops","twitter:title":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH - NBN23","twitter:description":"Tras conseguir las firmas de Guinea y Ben\u00edn, NBN23 cierra ahora un acuerdo con la Federaci\u00f3n de Baloncesto de Togo. 0 acuerdos en 5 a\u00f1os y 3 acuerdos en poco menos de un mes. Esa es la explosi\u00f3n que ha vivido NBN23 en \u00c1frica en las \u00faltimas semanas. La \u00faltima en unirse a Swish ha","twitter:creator":"@swishallhoops","twitter:image":"https:\/\/nbn23.com\/wp-content\/uploads\/2021\/03\/Federacion-de-Baloncesto-de-Togo.png"},"aioseo_meta_data":{"post_id":"10949","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-01-12 14:11:39","updated":"2025-06-05 08:20:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nbn23.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nbn23.com\/es\/category\/noticia\/\" title=\"Noticia\">Noticia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nbn23.com\/es\/"},{"label":"Noticia","link":"https:\/\/nbn23.com\/es\/category\/noticia\/"},{"label":"NBN23 COGE CARRERILLA EN \u00c1FRICA: TOGO TAMBI\u00c9N SE UNIR\u00c1 A SWISH","link":"https:\/\/nbn23.com\/es\/nbn23-coge-carrerilla-en-africa-togo-tambien-se-unira-a-swish\/"}],"_links":{"self":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/10949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/comments?post=10949"}],"version-history":[{"count":1,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/10949\/revisions"}],"predecessor-version":[{"id":10958,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/posts\/10949\/revisions\/10958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/media\/10950"}],"wp:attachment":[{"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/media?parent=10949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/categories?post=10949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nbn23.com\/es\/wp-json\/wp\/v2\/tags?post=10949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}